{"id":5074,"date":"2019-11-18T10:00:00","date_gmt":"2019-11-18T09:00:00","guid":{"rendered":"https:\/\/eurochange.es\/blog\/2019\/11\/18\/nuevos-billetes-de-100-dolares-de-hong-kong\/"},"modified":"2023-07-25T14:29:03","modified_gmt":"2023-07-25T12:29:03","slug":"nuevos-billetes-de-100-dolares-de-hong-kong","status":"publish","type":"post","link":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/","title":{"rendered":"Nuevos billetes de 100 D\u00f3lares de Hong Kong"},"content":{"rendered":"<p>Las Autoridades Monetarias de Hong Kong est&aacute;n en proceso de emisi&oacute;n de una nueva familia de billetes de D&oacute;lar de Hong Kong, la serie 2018. El primer billete que se emiti&oacute; de esta nueva serie fue el de <a href=\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-500-dolares-de-hong-kong\/\" target=\"_blank\" rel=\"noopener\">500 D&oacute;lares de Hong Kong<\/a>, despu&eacute;s lleg&oacute; el turno del billete de 1000 D&oacute;lares y el &uacute;ltimo que se ha emitido es el de 100 D&oacute;lares de Hong Kong.<\/p>\n<div style=\"text-align:center\">\n<figure class=\"image\" style=\"display:inline-block\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"Billetes de 100, 500 y 1000 D\u00f3lares de Hong Kong\" height=\"368\" src=\"https:\/\/eurochange.es\/uploads\/blog\/2019\/11\/nuevos-billetes-de-dolar-de-hong-kong.jpg\" width=\"350\" \/><figcaption>Billetes de 100, 500 y 1000 D&oacute;lares de Hong Kong<\/figcaption><\/figure>\n<\/div>\n<p>&nbsp;<\/p>\n<h2>Dise&ntilde;o del nuevo billete de 100 HKD<\/h2>\n<p>Para esta nueva emisi&oacute;n los diferentes bancos emisores del D&oacute;lar de Hong Kong se han puesto de acuerdo para <strong>estandarizar el dise&ntilde;o y que los billetes sean m&aacute;s f&aacute;cilmente reconocibles<\/strong>. Adem&aacute;s, el reverso de los billetes tiene una orientaci&oacute;n vertical en lugar de la tradicional orientaci&oacute;n horizontal.<\/p>\n<p>La tem&aacute;tica de los billetes de 100 D&oacute;lares de Hong Kong es su <strong>legado cultural que se expresa con varias representaciones de la &oacute;pera Cantonesa<\/strong> en los reversos de los billetes. En los anversos se mantienen los mismos dise&ntilde;os que en los dem&aacute;s billetes de la serie: la Torre del Banco de China, la Torre del Standard Chartered Bank y el le&oacute;n emblema del HSBC. &nbsp;<\/p>\n<p>Estos <strong>nuevos billetes convivir&aacute;n en circulaci&oacute;n<\/strong> con las series anteriores hasta nuevo aviso por parte de las Autoridades Monetarias de Hong Kong.<\/p>\n<p>&nbsp;<\/p>\n<h2>&iquest;Necesitas comprar D&oacute;lares de Hong Kong?<\/h2>\n<p>Haz tu pedido hoy al mejor precio en nuestra p&aacute;gina web.<\/p>\n<p style=\"text-align:center\"><a href=\"https:\/\/eurochange.es\/cotizaciones\/dolar-hong-kong\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" alt=\"Comprar D\u00f3lares de Hong Kong al mejor precio\" height=\"239\" src=\"https:\/\/eurochange.es\/uploads\/blog\/banners-blog\/comprar-dolares-de-hong-kong-online.jpg\" width=\"350\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevos billetes de D\u00f3lar de Hong Kong en circulaci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":1250,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1561,1522],"tags":[],"class_list":["post-5074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dolar-de-hong-kong","category-monedas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nuevos billetes de 100 D\u00f3lares de Hong Kong<\/title>\n<meta name=\"description\" content=\"Existen tres billetes de D\u00f3lar de Hong Kong en circulaci\u00f3n de la serie 2018. Los billetes de 100, 500 y 1000 D\u00f3lares estar\u00e1n en circulaci\u00f3n junto con las otras denominaciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevos billetes de 100 D\u00f3lares de Hong Kong\" \/>\n<meta property=\"og:description\" content=\"Existen tres billetes de D\u00f3lar de Hong Kong en circulaci\u00f3n de la serie 2018. Los billetes de 100, 500 y 1000 D\u00f3lares estar\u00e1n en circulaci\u00f3n junto con las otras denominaciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurochange Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-18T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T12:29:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eurochange\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"eurochange\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/\"},\"author\":{\"name\":\"eurochange\",\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/person\/87b2ef600c297e4e4d93d717d3b09539\"},\"headline\":\"Nuevos billetes de 100 D\u00f3lares de Hong Kong\",\"datePublished\":\"2019-11-18T09:00:00+00:00\",\"dateModified\":\"2023-07-25T12:29:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/\"},\"wordCount\":295,\"publisher\":{\"@id\":\"https:\/\/eurochange.es\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg\",\"articleSection\":[\"D\u00f3lar de Hong Kong\",\"Monedas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/\",\"url\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/\",\"name\":\"Nuevos billetes de 100 D\u00f3lares de Hong Kong\",\"isPartOf\":{\"@id\":\"https:\/\/eurochange.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg\",\"datePublished\":\"2019-11-18T09:00:00+00:00\",\"dateModified\":\"2023-07-25T12:29:03+00:00\",\"description\":\"Existen tres billetes de D\u00f3lar de Hong Kong en circulaci\u00f3n de la serie 2018. Los billetes de 100, 500 y 1000 D\u00f3lares estar\u00e1n en circulaci\u00f3n junto con las otras denominaciones.\",\"breadcrumb\":{\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#primaryimage\",\"url\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg\",\"contentUrl\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg\",\"width\":800,\"height\":522},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eurochange.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevos billetes de 100 D\u00f3lares de Hong Kong\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eurochange.es\/blog\/#website\",\"url\":\"https:\/\/eurochange.es\/blog\/\",\"name\":\"Eurochange Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eurochange.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eurochange.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eurochange.es\/blog\/#organization\",\"name\":\"Eurochange Blog\",\"url\":\"https:\/\/eurochange.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/12\/LOGO-LINKEDIN.jpg\",\"contentUrl\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/12\/LOGO-LINKEDIN.jpg\",\"width\":200,\"height\":200,\"caption\":\"Eurochange Blog\"},\"image\":{\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/person\/87b2ef600c297e4e4d93d717d3b09539\",\"name\":\"eurochange\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/614203bd6b0deb8f1785624071de1fe9951486c771703b7b8351050e1c0f567d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/614203bd6b0deb8f1785624071de1fe9951486c771703b7b8351050e1c0f567d?s=96&d=mm&r=g\",\"caption\":\"eurochange\"},\"sameAs\":[\"http:\/\/eurochange.es\/blog\"],\"url\":\"https:\/\/eurochange.es\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevos billetes de 100 D\u00f3lares de Hong Kong","description":"Existen tres billetes de D\u00f3lar de Hong Kong en circulaci\u00f3n de la serie 2018. Los billetes de 100, 500 y 1000 D\u00f3lares estar\u00e1n en circulaci\u00f3n junto con las otras denominaciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevos billetes de 100 D\u00f3lares de Hong Kong","og_description":"Existen tres billetes de D\u00f3lar de Hong Kong en circulaci\u00f3n de la serie 2018. Los billetes de 100, 500 y 1000 D\u00f3lares estar\u00e1n en circulaci\u00f3n junto con las otras denominaciones.","og_url":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/","og_site_name":"Eurochange Blog","article_published_time":"2019-11-18T09:00:00+00:00","article_modified_time":"2023-07-25T12:29:03+00:00","og_image":[{"width":800,"height":522,"url":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg","type":"image\/jpeg"}],"author":"eurochange","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"eurochange","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#article","isPartOf":{"@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/"},"author":{"name":"eurochange","@id":"https:\/\/eurochange.es\/blog\/#\/schema\/person\/87b2ef600c297e4e4d93d717d3b09539"},"headline":"Nuevos billetes de 100 D\u00f3lares de Hong Kong","datePublished":"2019-11-18T09:00:00+00:00","dateModified":"2023-07-25T12:29:03+00:00","mainEntityOfPage":{"@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/"},"wordCount":295,"publisher":{"@id":"https:\/\/eurochange.es\/blog\/#organization"},"image":{"@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#primaryimage"},"thumbnailUrl":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg","articleSection":["D\u00f3lar de Hong Kong","Monedas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/","url":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/","name":"Nuevos billetes de 100 D\u00f3lares de Hong Kong","isPartOf":{"@id":"https:\/\/eurochange.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#primaryimage"},"image":{"@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#primaryimage"},"thumbnailUrl":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg","datePublished":"2019-11-18T09:00:00+00:00","dateModified":"2023-07-25T12:29:03+00:00","description":"Existen tres billetes de D\u00f3lar de Hong Kong en circulaci\u00f3n de la serie 2018. Los billetes de 100, 500 y 1000 D\u00f3lares estar\u00e1n en circulaci\u00f3n junto con las otras denominaciones.","breadcrumb":{"@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#primaryimage","url":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg","contentUrl":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1573814335portada-hkd-jpg","width":800,"height":522},{"@type":"BreadcrumbList","@id":"https:\/\/eurochange.es\/blog\/monedas\/nuevos-billetes-de-100-dolares-de-hong-kong\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eurochange.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuevos billetes de 100 D\u00f3lares de Hong Kong"}]},{"@type":"WebSite","@id":"https:\/\/eurochange.es\/blog\/#website","url":"https:\/\/eurochange.es\/blog\/","name":"Eurochange Blog","description":"","publisher":{"@id":"https:\/\/eurochange.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurochange.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eurochange.es\/blog\/#organization","name":"Eurochange Blog","url":"https:\/\/eurochange.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurochange.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/12\/LOGO-LINKEDIN.jpg","contentUrl":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/12\/LOGO-LINKEDIN.jpg","width":200,"height":200,"caption":"Eurochange Blog"},"image":{"@id":"https:\/\/eurochange.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eurochange.es\/blog\/#\/schema\/person\/87b2ef600c297e4e4d93d717d3b09539","name":"eurochange","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurochange.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/614203bd6b0deb8f1785624071de1fe9951486c771703b7b8351050e1c0f567d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/614203bd6b0deb8f1785624071de1fe9951486c771703b7b8351050e1c0f567d?s=96&d=mm&r=g","caption":"eurochange"},"sameAs":["http:\/\/eurochange.es\/blog"],"url":"https:\/\/eurochange.es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/posts\/5074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/comments?post=5074"}],"version-history":[{"count":1,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/posts\/5074\/revisions"}],"predecessor-version":[{"id":5997,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/posts\/5074\/revisions\/5997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/media\/1250"}],"wp:attachment":[{"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/media?parent=5074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/categories?post=5074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/tags?post=5074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}