{"id":5201,"date":"2017-01-02T10:00:00","date_gmt":"2017-01-02T09:00:00","guid":{"rendered":"https:\/\/eurochange.es\/blog\/2017\/01\/02\/5-cosas-que-ver-en-moscu\/"},"modified":"2023-07-25T14:28:26","modified_gmt":"2023-07-25T12:28:26","slug":"5-cosas-que-ver-en-moscu","status":"publish","type":"post","link":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/","title":{"rendered":"5 cosas que ver en Mosc\u00fa"},"content":{"rendered":"<p>Con la llegada del a&ntilde;o nuevo un buen prop&oacute;sito puede ser planificar las vacaciones de 2017. Y si te vas a poner a ello, no te pierdas este post donde te recomendamos <strong>algunas de las mejores cosas que visitar en la capital Rusa<\/strong>.<\/p>\n<p style=\"text-align:center\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"Plaza Roja de Mosc\u00fa\" height=\"233\" src=\"https:\/\/eurochange.es\/uploads\/blog\/2017\/Moscu-Rusia-Moscow-Russia\/Plaza-Roja-Red-Square.jpg\" width=\"350\" \/><\/p>\n<p><strong>La Plaza Roja<\/strong><\/p>\n<p>La Plaza Roja se encuentra en el centro de Mosc&uacute;. Desde que Iv&aacute;n El Grande destruy&oacute; las casas de madera que se situaban en esta zona para mejorar la protecci&oacute;n del Kremlin, la plaza se ha utilizado para diversos fines: como campo de tiro, como plaza del mercado, para celebrar ceremonias p&uacute;blicas e incluso conciertos en los &uacute;ltimos a&ntilde;os.<\/p>\n<p><strong>Alrededor de la Plaza Roja<\/strong> encontrar&aacute;s el <strong>GUM <\/strong>(unos grandes almacenes creados en la &eacute;poca sovi&eacute;tica en los que se siguen vendiendo primeras marcas mundiales adem&aacute;s encontrar&aacute;s restaurantes y cines), la <strong>Catedral de San Basilio<\/strong> (templo ortodoxo conocido en casi todo el mundo como el emblema de la ciudad), el <strong>Museo Estatal de Historia<\/strong> (donde se exponen piezas destacadas de la historia del pa&iacute;s desde la prehistoria hasta el Siglo XX), el <strong>Mausoleo de Lenin<\/strong> (donde se encuentra su cuerpo momificado y las tumbas de otros militares y presidentes rusos) y el <strong>Kremlin <\/strong>(compuesto por varios edificios, catedrales y otros espacios donde destaca el edificio de gobierno).<\/p>\n<p style=\"text-align:center\"><img decoding=\"async\" alt=\"Diferentes fotos de estaciones de metro de Mosc\u00fa\" height=\"270\" src=\"https:\/\/eurochange.es\/uploads\/blog\/2017\/Moscu-Rusia-Moscow-Russia\/Metro-Moscu-Moscow.jpg\" width=\"350\" \/><\/p>\n<p><strong>Metro de Mosc&uacute;<\/strong><\/p>\n<p>El Metro de Mosc&uacute; no es s&oacute;lo una manera r&aacute;pida de moverte por la ciudad, sino que <strong>es una atracci&oacute;n tur&iacute;stica m&aacute;s<\/strong>. Algunas de sus estaciones son espacios en los que podr&aacute;s disfrutar de <strong>pinturas, mosaicos y esculturas<\/strong> como si estuvieses en un museo diseminado por toda la ciudad. Y si eres de los que se pierde en el metro, no te preocupes, hay visitas guiadas que te lo pondr&aacute;n muy f&aacute;cil.<\/p>\n<p style=\"text-align:center\"><img decoding=\"async\" alt=\"Entrada principal del Parque Gorki en Mosc\u00fa\" height=\"197\" src=\"https:\/\/eurochange.es\/uploads\/blog\/2017\/Moscu-Rusia-Moscow-Russia\/parque-Gorki-Gorky-park.jpg\" width=\"350\" \/><\/p>\n<p><strong>El Parque Gorki<\/strong><\/p>\n<p>Este parque est&aacute; situado a orillas del r&iacute;o Moldova. Es una extensi&oacute;n bastante grande que en sus inicios estaba destinada al acceso al entretenimiento y la cultura de las clases trabajadoras. Hoy en d&iacute;a es un parque con <strong>m&uacute;ltiples espacios para disfrutar<\/strong>: servicios de alquiler de bicicletas y patines, un parque de atracciones, instalaciones deportivas, lagos en los que dar un paseo en barca, caf&eacute;s y restaurantes, adem&aacute;s de pista de hielo en invierno y playas urbanas en verano. Un lugar donde disfrutar en pareja, con amigos o en familia.<\/p>\n<p style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" alt=\"Fachada principal del Teatro Bolsh\u00f3i en Mosc\u00fa\" height=\"258\" src=\"https:\/\/eurochange.es\/uploads\/blog\/2017\/Moscu-Rusia-Moscow-Russia\/Teatro-Bolshoi-Theater.jpg\" width=\"350\" \/><\/p>\n<p><strong>El Teatro Bolsh&oacute;i<\/strong><\/p>\n<p>Se trata de <strong>uno de los teatros m&aacute;s importantes del mundo<\/strong>. Tanto si te gusta la &oacute;pera o el ballet como si no eres el mayor aficionado, te recomendamos que compres una entrada y disfrutes del espect&aacute;culo, del edificio, de la decoraci&oacute;n,&hellip; Ya que fue remodelado a principios de los a&ntilde;os 2000 para devolverle el esplendor de la &eacute;poca de su construcci&oacute;n. Una manera de transportarte a la Rusia del Siglo XIX.<\/p>\n<p style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" alt=\"Exposici\u00f3n de objetos en el Museo de la Cosmon\u00e1utica\" height=\"224\" src=\"https:\/\/eurochange.es\/uploads\/blog\/2017\/Moscu-Rusia-Moscow-Russia\/museo-cosmonautica-cosmonautic-museum.JPG\" width=\"350\" \/><\/p>\n<p><strong>Museo de la Cosmon&aacute;utica<\/strong><\/p>\n<p>Este museo est&aacute; dedicado a <strong>explicar la carrera espacial rusa y la exploraci&oacute;n espacial <\/strong>casi desde sus inicios. En &eacute;l se exponen partes de naves, objetos del espacio, trajes espaciales y material audiovisual. Adem&aacute;s hay un caf&eacute; donde podr&aacute;s relajarte durante tu visita. En el exterior del museo se encuentra el Monumento a los Conquistadores del Espacio, con m&aacute;s de 100 metros de altura.<\/p>\n<p>&nbsp;<\/p>\n<p>Si ya te hemos animado y vas a comenzar a planificar tu viaje, <strong>recuerda que necesitar&aacute;s Rublos Rusos<\/strong> para poder pagar tus gastos en efectivo. Puedes <a href=\"https:\/\/eurochange.es\/cotizaciones\/rublo-ruso\" target=\"_blank\" rel=\"noopener\"><strong>comprar los Rublos Rusos<\/strong><\/a> que necesites para tu viaje ahora mismo en nuestra web y as&iacute; podr&aacute;s centrarte en disfrutar tu estancia.<\/p>\n<p>&iexcl;Que tengas un buen viaje!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si planeas un viaje a Mosc\u00fa, te recomendamos 5 cosas que visitar<\/p>\n","protected":false},"author":1,"featured_media":902,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1593,1523],"tags":[],"class_list":["post-5201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rusia","category-viajes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Consejos para viajar a Mosc\u00fa | Eurochange.es<\/title>\n<meta name=\"description\" content=\"Antes de preparar tu viaje a Mosc\u00fa, Rusia, te vendr\u00e1 ver tener algunas consideraciones previas que pueden ser la respuesta a algunas de tus dudas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consejos para viajar a Mosc\u00fa | Eurochange.es\" \/>\n<meta property=\"og:description\" content=\"Antes de preparar tu viaje a Mosc\u00fa, Rusia, te vendr\u00e1 ver tener algunas consideraciones previas que pueden ser la respuesta a algunas de tus dudas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurochange Blog\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-02T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T12:28:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eurochange\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"eurochange\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/\"},\"author\":{\"name\":\"eurochange\",\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/person\/87b2ef600c297e4e4d93d717d3b09539\"},\"headline\":\"5 cosas que ver en Mosc\u00fa\",\"datePublished\":\"2017-01-02T09:00:00+00:00\",\"dateModified\":\"2023-07-25T12:28:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/\"},\"wordCount\":670,\"publisher\":{\"@id\":\"https:\/\/eurochange.es\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg\",\"articleSection\":[\"Rusia\",\"Viajes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/\",\"url\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/\",\"name\":\"Consejos para viajar a Mosc\u00fa | Eurochange.es\",\"isPartOf\":{\"@id\":\"https:\/\/eurochange.es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg\",\"datePublished\":\"2017-01-02T09:00:00+00:00\",\"dateModified\":\"2023-07-25T12:28:26+00:00\",\"description\":\"Antes de preparar tu viaje a Mosc\u00fa, Rusia, te vendr\u00e1 ver tener algunas consideraciones previas que pueden ser la respuesta a algunas de tus dudas.\",\"breadcrumb\":{\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#primaryimage\",\"url\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg\",\"contentUrl\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg\",\"width\":240,\"height\":160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eurochange.es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 cosas que ver en Mosc\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eurochange.es\/blog\/#website\",\"url\":\"https:\/\/eurochange.es\/blog\/\",\"name\":\"Eurochange Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eurochange.es\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eurochange.es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eurochange.es\/blog\/#organization\",\"name\":\"Eurochange Blog\",\"url\":\"https:\/\/eurochange.es\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/12\/LOGO-LINKEDIN.jpg\",\"contentUrl\":\"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/12\/LOGO-LINKEDIN.jpg\",\"width\":200,\"height\":200,\"caption\":\"Eurochange Blog\"},\"image\":{\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/person\/87b2ef600c297e4e4d93d717d3b09539\",\"name\":\"eurochange\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/eurochange.es\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/614203bd6b0deb8f1785624071de1fe9951486c771703b7b8351050e1c0f567d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/614203bd6b0deb8f1785624071de1fe9951486c771703b7b8351050e1c0f567d?s=96&d=mm&r=g\",\"caption\":\"eurochange\"},\"sameAs\":[\"http:\/\/eurochange.es\/blog\"],\"url\":\"https:\/\/eurochange.es\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consejos para viajar a Mosc\u00fa | Eurochange.es","description":"Antes de preparar tu viaje a Mosc\u00fa, Rusia, te vendr\u00e1 ver tener algunas consideraciones previas que pueden ser la respuesta a algunas de tus dudas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/","og_locale":"es_ES","og_type":"article","og_title":"Consejos para viajar a Mosc\u00fa | Eurochange.es","og_description":"Antes de preparar tu viaje a Mosc\u00fa, Rusia, te vendr\u00e1 ver tener algunas consideraciones previas que pueden ser la respuesta a algunas de tus dudas.","og_url":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/","og_site_name":"Eurochange Blog","article_published_time":"2017-01-02T09:00:00+00:00","article_modified_time":"2023-07-25T12:28:26+00:00","og_image":[{"width":240,"height":160,"url":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg","type":"image\/jpeg"}],"author":"eurochange","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"eurochange","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#article","isPartOf":{"@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/"},"author":{"name":"eurochange","@id":"https:\/\/eurochange.es\/blog\/#\/schema\/person\/87b2ef600c297e4e4d93d717d3b09539"},"headline":"5 cosas que ver en Mosc\u00fa","datePublished":"2017-01-02T09:00:00+00:00","dateModified":"2023-07-25T12:28:26+00:00","mainEntityOfPage":{"@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/"},"wordCount":670,"publisher":{"@id":"https:\/\/eurochange.es\/blog\/#organization"},"image":{"@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#primaryimage"},"thumbnailUrl":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg","articleSection":["Rusia","Viajes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/","url":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/","name":"Consejos para viajar a Mosc\u00fa | Eurochange.es","isPartOf":{"@id":"https:\/\/eurochange.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#primaryimage"},"image":{"@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#primaryimage"},"thumbnailUrl":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg","datePublished":"2017-01-02T09:00:00+00:00","dateModified":"2023-07-25T12:28:26+00:00","description":"Antes de preparar tu viaje a Mosc\u00fa, Rusia, te vendr\u00e1 ver tener algunas consideraciones previas que pueden ser la respuesta a algunas de tus dudas.","breadcrumb":{"@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#primaryimage","url":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg","contentUrl":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/07\/1483449970plaza-roja-red-square-jpg","width":240,"height":160},{"@type":"BreadcrumbList","@id":"https:\/\/eurochange.es\/blog\/viajes\/5-cosas-que-ver-en-moscu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eurochange.es\/blog\/"},{"@type":"ListItem","position":2,"name":"5 cosas que ver en Mosc\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/eurochange.es\/blog\/#website","url":"https:\/\/eurochange.es\/blog\/","name":"Eurochange Blog","description":"","publisher":{"@id":"https:\/\/eurochange.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurochange.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eurochange.es\/blog\/#organization","name":"Eurochange Blog","url":"https:\/\/eurochange.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurochange.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/12\/LOGO-LINKEDIN.jpg","contentUrl":"https:\/\/eurochange.es\/blog\/wp-content\/uploads\/2023\/12\/LOGO-LINKEDIN.jpg","width":200,"height":200,"caption":"Eurochange Blog"},"image":{"@id":"https:\/\/eurochange.es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eurochange.es\/blog\/#\/schema\/person\/87b2ef600c297e4e4d93d717d3b09539","name":"eurochange","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurochange.es\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/614203bd6b0deb8f1785624071de1fe9951486c771703b7b8351050e1c0f567d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/614203bd6b0deb8f1785624071de1fe9951486c771703b7b8351050e1c0f567d?s=96&d=mm&r=g","caption":"eurochange"},"sameAs":["http:\/\/eurochange.es\/blog"],"url":"https:\/\/eurochange.es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/posts\/5201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/comments?post=5201"}],"version-history":[{"count":1,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/posts\/5201\/revisions"}],"predecessor-version":[{"id":5881,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/posts\/5201\/revisions\/5881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/media\/902"}],"wp:attachment":[{"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/media?parent=5201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/categories?post=5201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurochange.es\/blog\/wp-json\/wp\/v2\/tags?post=5201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}